{"id":4879,"date":"2024-11-04T20:29:23","date_gmt":"2024-11-04T20:29:23","guid":{"rendered":"https:\/\/talbotthrive.org\/?page_id=4879"},"modified":"2025-06-04T19:06:27","modified_gmt":"2025-06-04T19:06:27","slug":"bike-request","status":"publish","type":"page","link":"https:\/\/talbotthrive.org\/es\/bike-request\/","title":{"rendered":"Solicitud de bicicleta"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Frequently Asked Questions&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;7px|||||&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Bike Request Form&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Nunito|Nunito_weight|||||||&#8221; title_text_color=&#8221;#111111&#8243; title_font_size=&#8221;35px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Occasionally Talbot Thrive receives donations of used bikes. Once refurbished we offer them to the community at no charge.<\/p>\n<p>To contact us about donating a bike, email <a href=\"mailto:heather@talbotthrive.org\">heather@talbotthrive.org<\/a>.<\/p>\n<p>[\/et_pb_text][wpforms_selector _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; form_id=&#8221;4871&#8243; show_title=&#8221;off&#8221; show_desc=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/wpforms_selector][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Occasionally Talbot Thrive receives donations of used bikes. Once refurbished we offer them to the community at no charge. To contact us about donating a bike, email heather@talbotthrive.org.<div class=\"et_pb_module wpforms_selector wpforms_selector_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-4871\"><form id=\"wpforms-form-4871\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"4871\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/4879\" data-token=\"db398140a9035d2edc9b971470b36af7\" data-token-time=\"1778706833\"><div class=\"wpforms-head-container\"><\/div><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-4871-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\">Parent\/Guardian Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-4871-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" required><label for=\"wpforms-4871-field_1\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-4871-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" required><label for=\"wpforms-4871-field_1-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/div><div id=\"wpforms-4871-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-4871-field_5\">Phone Number <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-4871-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-4871-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-4871-field_2\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-4871-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-4871-field_4-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"4\"><label class=\"wpforms-field-label\">What age is the child? (please complete a separate form for each child) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-4871-field_4\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_4_1\" name=\"wpforms[fields][4][]\" value=\"Age 2-4 (Balance Bike)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_4_1\">Age 2-4 (Balance Bike)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_4_2\" name=\"wpforms[fields][4][]\" value=\"Age 4-7 (Small 20&quot; Wheel)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_4_2\">Age 4-7 (Small 20\" Wheel)<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_4_3\" name=\"wpforms[fields][4][]\" value=\"Age 8-10 (Medium 24&quot; Wheel)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_4_3\">Age 8-10 (Medium 24\" Wheel)<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_4_4\" name=\"wpforms[fields][4][]\" value=\"Ages 12-14 (Large 26&quot; Wheel)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_4_4\">Ages 12-14 (Large 26\" Wheel)<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_4_5\" name=\"wpforms[fields][4][]\" value=\"Adult Size Bike (Child Height 5&#039; and up)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_4_5\">Adult Size Bike (Child Height 5' and up)<\/label><\/li><\/ul><\/div><div id=\"wpforms-4871-field_13-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"13\"><label class=\"wpforms-field-label\">Gender (unfortunately, most kid&#039;s bikes are manufactured with gender specific designs)<\/label><ul id=\"wpforms-4871-field_13\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_13_1\" name=\"wpforms[fields][13][]\" value=\"Girl\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_13_1\">Girl<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_13_2\" name=\"wpforms[fields][13][]\" value=\"Boy\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_13_2\">Boy<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_13_3\" name=\"wpforms[fields][13][]\" value=\"I&#039;ll take any bike!\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_13_3\">I'll take any bike!<\/label><\/li><\/ul><\/div><div id=\"wpforms-4871-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-4871-field_11\">Approximate Height (inches)<\/label><input type=\"text\" id=\"wpforms-4871-field_11\" class=\"wpforms-field-medium\" name=\"wpforms[fields][11]\" ><\/div><div id=\"wpforms-4871-field_12-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"12\"><label class=\"wpforms-field-label\">Does Your Child Also Need a Helmet?<\/label><ul id=\"wpforms-4871-field_12\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_12_1\" name=\"wpforms[fields][12][]\" value=\"Yes\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_12_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4871-field_12_2\" name=\"wpforms[fields][12][]\" value=\"No\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4871-field_12_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-4871-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-4871-field_6\">Address<\/label><input type=\"text\" id=\"wpforms-4871-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" ><\/div><div id=\"wpforms-4871-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-4871-field_7\">City\/Town<\/label><input type=\"text\" id=\"wpforms-4871-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" ><\/div><div id=\"wpforms-4871-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-4871-field_8\">State<\/label><input type=\"text\" id=\"wpforms-4871-field_8\" class=\"wpforms-field-medium\" name=\"wpforms[fields][8]\" ><\/div><div id=\"wpforms-4871-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-4871-field_9\">Zip<\/label><input type=\"text\" id=\"wpforms-4871-field_9\" class=\"wpforms-field-medium\" name=\"wpforms[fields][9]\" ><\/div><div id=\"wpforms-4871-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-4871-field_3\">How did you hear about Talbot Thrive?<\/label><textarea id=\"wpforms-4871-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"4871\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/pages\/4879\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-4871\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img src=\"https:\/\/talbotthrive.org\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"_links":{"self":[{"href":"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/pages\/4879"}],"collection":[{"href":"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/comments?post=4879"}],"version-history":[{"count":4,"href":"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/pages\/4879\/revisions"}],"predecessor-version":[{"id":5474,"href":"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/pages\/4879\/revisions\/5474"}],"wp:attachment":[{"href":"https:\/\/talbotthrive.org\/es\/wp-json\/wp\/v2\/media?parent=4879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}